{"id":3306,"date":"2023-03-20T13:27:47","date_gmt":"2023-03-20T11:27:47","guid":{"rendered":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg"},"modified":"2023-03-20T13:27:47","modified_gmt":"2023-03-20T11:27:47","slug":"imgm4750_fullsize_fotograaf-lauri-laan-2","status":"inherit","type":"attachment","link":"https:\/\/restoranmoon.ee\/en\/gallery\/imgm4750_fullsize_fotograaf-lauri-laan-2\/","title":{"rendered":"IMGM4750_fullsize_fotograaf.lauri.laan"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-3306","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>IMGM4750_fullsize_fotograaf.lauri.laan - Restoran Moon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IMGM4750_fullsize_fotograaf.lauri.laan - Restoran Moon\" \/>\n<meta property=\"og:url\" content=\"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Restoran Moon\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kohvikmoon\" \/>\n<meta property=\"og:image\" content=\"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg\",\"url\":\"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg\",\"name\":\"IMGM4750_fullsize_fotograaf.lauri.laan - Restoran Moon\",\"isPartOf\":{\"@id\":\"https:\/\/restoranmoon.ee\/#website\"},\"datePublished\":\"2023-03-20T11:27:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/restoranmoon.ee\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gallery\",\"item\":\"https:\/\/restoranmoon.ee\/en\/gallery\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IMGM4750_fullsize_fotograaf.lauri.laan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/restoranmoon.ee\/#website\",\"url\":\"https:\/\/restoranmoon.ee\/\",\"name\":\"Restoran Moon\",\"description\":\"Modernne Slaavi k\u00f6\u00f6k tehtud suure kirega!\",\"publisher\":{\"@id\":\"https:\/\/restoranmoon.ee\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/restoranmoon.ee\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/restoranmoon.ee\/#organization\",\"name\":\"Restoran Moon\",\"url\":\"https:\/\/restoranmoon.ee\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/restoranmoon.ee\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2016\/08\/moon-color-on-white.png\",\"contentUrl\":\"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2016\/08\/moon-color-on-white.png\",\"width\":1679,\"height\":1083,\"caption\":\"Restoran Moon\"},\"image\":{\"@id\":\"https:\/\/restoranmoon.ee\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/kohvikmoon\",\"https:\/\/www.instagram.com\/restoranmoon\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IMGM4750_fullsize_fotograaf.lauri.laan - Restoran Moon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg","og_locale":"en_US","og_type":"article","og_title":"IMGM4750_fullsize_fotograaf.lauri.laan - Restoran Moon","og_url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg","og_site_name":"Restoran Moon","article_publisher":"https:\/\/www.facebook.com\/kohvikmoon","og_image":[{"width":1280,"height":1920,"url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg","url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg","name":"IMGM4750_fullsize_fotograaf.lauri.laan - Restoran Moon","isPartOf":{"@id":"https:\/\/restoranmoon.ee\/#website"},"datePublished":"2023-03-20T11:27:47+00:00","breadcrumb":{"@id":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/restoranmoon.ee\/en\/"},{"@type":"ListItem","position":2,"name":"Gallery","item":"https:\/\/restoranmoon.ee\/en\/gallery\/"},{"@type":"ListItem","position":3,"name":"IMGM4750_fullsize_fotograaf.lauri.laan"}]},{"@type":"WebSite","@id":"https:\/\/restoranmoon.ee\/#website","url":"https:\/\/restoranmoon.ee\/","name":"Restoran Moon","description":"Modernne Slaavi k\u00f6\u00f6k tehtud suure kirega!","publisher":{"@id":"https:\/\/restoranmoon.ee\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/restoranmoon.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/restoranmoon.ee\/#organization","name":"Restoran Moon","url":"https:\/\/restoranmoon.ee\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/restoranmoon.ee\/#\/schema\/logo\/image\/","url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2016\/08\/moon-color-on-white.png","contentUrl":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2016\/08\/moon-color-on-white.png","width":1679,"height":1083,"caption":"Restoran Moon"},"image":{"@id":"https:\/\/restoranmoon.ee\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kohvikmoon","https:\/\/www.instagram.com\/restoranmoon"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-200x300.jpg 200w, https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-600x900.jpg 600w, https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-683x1024.jpg 683w, https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-768x1152.jpg 768w, https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-1024x1536.jpg 1024w, https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg 1280w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":1920,"file":"2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg","filesize":247065,"sizes":{"woocommerce_thumbnail":{"file":"imgm4750_fullsize_fotograaf.lauri_.laan_-300x300.jpg","width":300,"height":300,"filesize":46807,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-300x300.jpg"},"woocommerce_gallery_thumbnail":{"file":"imgm4750_fullsize_fotograaf.lauri_.laan_-100x100.jpg","width":100,"height":100,"filesize":31384,"mime_type":"image\/jpeg","source_url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-100x100.jpg"},"woocommerce_single":{"file":"imgm4750_fullsize_fotograaf.lauri_.laan_-600x900.jpg","width":600,"height":900,"filesize":95849,"mime_type":"image\/jpeg","source_url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-600x900.jpg"},"medium":{"file":"imgm4750_fullsize_fotograaf.lauri_.laan_-200x300.jpg","width":200,"height":300,"filesize":40806,"mime_type":"image\/jpeg","source_url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-200x300.jpg"},"large":{"file":"imgm4750_fullsize_fotograaf.lauri_.laan_-683x1024.jpg","width":683,"height":1024,"filesize":110190,"mime_type":"image\/jpeg","source_url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-683x1024.jpg"},"thumbnail":{"file":"imgm4750_fullsize_fotograaf.lauri_.laan_-150x150.jpg","width":150,"height":150,"filesize":34436,"mime_type":"image\/jpeg","source_url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-150x150.jpg"},"medium_large":{"file":"imgm4750_fullsize_fotograaf.lauri_.laan_-768x1152.jpg","width":768,"height":1152,"filesize":125808,"mime_type":"image\/jpeg","source_url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-768x1152.jpg"},"1536x1536":{"file":"imgm4750_fullsize_fotograaf.lauri_.laan_-1024x1536.jpg","width":1024,"height":1536,"filesize":178150,"mime_type":"image\/jpeg","source_url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-1024x1536.jpg"},"risotto_webnus_tabs_img":{"file":"imgm4750_fullsize_fotograaf.lauri_.laan_-164x124.jpg","width":164,"height":124,"filesize":33831,"mime_type":"image\/jpeg","source_url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-164x124.jpg"},"risotto_webnus_blog3_img":{"file":"imgm4750_fullsize_fotograaf.lauri_.laan_-420x280.jpg","width":420,"height":280,"filesize":50189,"mime_type":"image\/jpeg","source_url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-420x280.jpg"},"risotto_webnus_blog2_img":{"file":"imgm4750_fullsize_fotograaf.lauri_.laan_-420x330.jpg","width":420,"height":330,"filesize":54190,"mime_type":"image\/jpeg","source_url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-420x330.jpg"},"risotto_webnus_square_img":{"file":"imgm4750_fullsize_fotograaf.lauri_.laan_-460x460.jpg","width":460,"height":460,"filesize":64125,"mime_type":"image\/jpeg","source_url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-460x460.jpg"},"risotto_webnus_post_img":{"file":"imgm4750_fullsize_fotograaf.lauri_.laan_-670x374.jpg","width":670,"height":374,"filesize":66314,"mime_type":"image\/jpeg","source_url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-670x374.jpg"},"risotto_webnus_latest_cover":{"file":"imgm4750_fullsize_fotograaf.lauri_.laan_-690x460.jpg","width":690,"height":460,"filesize":75386,"mime_type":"image\/jpeg","source_url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-690x460.jpg"},"risotto_webnus_latestfromblog":{"file":"imgm4750_fullsize_fotograaf.lauri_.laan_-720x388.jpg","width":720,"height":388,"filesize":69748,"mime_type":"image\/jpeg","source_url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_-720x388.jpg"},"full":{"file":"imgm4750_fullsize_fotograaf.lauri_.laan_.jpg","width":1280,"height":1920,"mime_type":"image\/jpeg","source_url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg"}},"image_meta":{"aperture":"3.5","credit":"LAURI LAAN","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1665753807","copyright":"COPYRIGHT lauri@non.ee","focal_length":"100","iso":"200","shutter_speed":"0.005","title":"","orientation":"0","keywords":[]}},"post":518,"source_url":"https:\/\/restoranmoon.ee\/wp-content\/uploads\/2023\/03\/imgm4750_fullsize_fotograaf.lauri_.laan_.jpg","_links":{"self":[{"href":"https:\/\/restoranmoon.ee\/en\/wp-json\/wp\/v2\/media\/3306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/restoranmoon.ee\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/restoranmoon.ee\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/restoranmoon.ee\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/restoranmoon.ee\/en\/wp-json\/wp\/v2\/comments?post=3306"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":518,"href":"https:\/\/restoranmoon.ee\/en\/wp-json\/wp\/v2\/pages\/518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}